{"id":36,"count":1,"description":"","link":"http:\/\/www.wxcljx.com\/index.php\/category\/rolling-cylinder\/","name":"Rolling cylinder","slug":"rolling-cylinder","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/www.wxcljx.com\/index.php\/wp-json\/wp\/v2\/categories\/36","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.wxcljx.com\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/www.wxcljx.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/www.wxcljx.com\/index.php\/wp-json\/wp\/v2\/posts?categories=36"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}